{"id":176,"date":"2023-04-21T11:31:08","date_gmt":"2023-04-21T09:31:08","guid":{"rendered":"https:\/\/www.plasnor.com\/?p=176"},"modified":"2023-04-23T17:47:47","modified_gmt":"2023-04-23T15:47:47","slug":"03-que-tipo-de-cola-es-necesario-aplicar","status":"publish","type":"post","link":"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/","title":{"rendered":"03. \u00bfQUE TIPO DE COLA ES NECESARIO APLICAR?"},"content":{"rendered":"<p>El pegamento debe ser PUR. No trate de aplicar otros pegamentos, nuestra experiencia nos dice que nunca funcionan correctamente. Nosotros recomendamos las siguientes referencias: Kleiberit ref. 709.3, Henkel ref. QR4663 o Jowat 609.20. Cualquier otro pegamento caliente PUR deber\u00eda funcionar bien. El pegamento debe alcanzar una temperatura de hasta 140\u00baC para que sea suficientemente l\u00edquido. El rodillo a trav\u00e9s del que se aplica el pegamento debe estar a una temperatura de unos 125\u00baC.<\/p>\n<p><a href=\"http:\/\/www.henkel.es\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-166\" src=\"https:\/\/www.plasnor.com\/wp-content\/uploads\/2023\/04\/icono-link2.gif\" alt=\"\" width=\"22\" height=\"16\" \/> <em><strong>M\u00e1s informaci\u00f3n<\/strong><\/em><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pegamento debe ser PUR. No trate de aplicar otros pegamentos, nuestra experiencia nos dice que nunca funcionan &#8230; <a title=\"03. \u00bfQUE TIPO DE COLA ES NECESARIO APLICAR?\" class=\"read-more\" href=\"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/\" aria-label=\"Leer m\u00e1s sobre 03. \u00bfQUE TIPO DE COLA ES NECESARIO APLICAR?\">[ + info ]<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>03. \u00bfQUE TIPO DE COLA ES NECESARIO APLICAR? - Plasnor<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"03. \u00bfQUE TIPO DE COLA ES NECESARIO APLICAR? - Plasnor\" \/>\n<meta property=\"og:description\" content=\"El pegamento debe ser PUR. No trate de aplicar otros pegamentos, nuestra experiencia nos dice que nunca funcionan ... [ + info ]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/\" \/>\n<meta property=\"og:site_name\" content=\"Plasnor\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-21T09:31:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-23T15:47:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.plasnor.com\/wp-content\/uploads\/2023\/04\/icono-link2.gif\" \/>\n<meta name=\"author\" content=\"adminadaki@plasnor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/\"},\"author\":{\"name\":\"adminadaki@plasnor\",\"@id\":\"https:\/\/wp.plasnor.com\/es\/#\/schema\/person\/51769332fbe59a0095b15728faedad84\"},\"headline\":\"03. \u00bfQUE TIPO DE COLA ES NECESARIO APLICAR?\",\"datePublished\":\"2023-04-21T09:31:08+00:00\",\"dateModified\":\"2023-04-23T15:47:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/\"},\"wordCount\":85,\"publisher\":{\"@id\":\"https:\/\/wp.plasnor.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.plasnor.com\/wp-content\/uploads\/2023\/04\/icono-link2.gif\",\"articleSection\":[\"FAQ\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/\",\"url\":\"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/\",\"name\":\"03. \u00bfQUE TIPO DE COLA ES NECESARIO APLICAR? - Plasnor\",\"isPartOf\":{\"@id\":\"https:\/\/wp.plasnor.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.plasnor.com\/wp-content\/uploads\/2023\/04\/icono-link2.gif\",\"datePublished\":\"2023-04-21T09:31:08+00:00\",\"dateModified\":\"2023-04-23T15:47:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/#primaryimage\",\"url\":\"https:\/\/www.plasnor.com\/wp-content\/uploads\/2023\/04\/icono-link2.gif\",\"contentUrl\":\"https:\/\/www.plasnor.com\/wp-content\/uploads\/2023\/04\/icono-link2.gif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/wp.plasnor.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQ\",\"item\":\"https:\/\/wp.plasnor.com\/es\/category\/faq\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"03. \u00bfQUE TIPO DE COLA ES NECESARIO APLICAR?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wp.plasnor.com\/es\/#website\",\"url\":\"https:\/\/wp.plasnor.com\/es\/\",\"name\":\"Plasnor\",\"description\":\"Especialistas en extrusi\u00f3n y termoconformado\",\"publisher\":{\"@id\":\"https:\/\/wp.plasnor.com\/es\/#organization\"},\"alternateName\":\"Plasnor\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wp.plasnor.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/wp.plasnor.com\/es\/#organization\",\"name\":\"Plasnor\",\"alternateName\":\"Plasnor\",\"url\":\"https:\/\/wp.plasnor.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/wp.plasnor.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.plasnor.com\/wp-content\/uploads\/2023\/04\/logotipo-plasnor.jpg\",\"contentUrl\":\"https:\/\/www.plasnor.com\/wp-content\/uploads\/2023\/04\/logotipo-plasnor.jpg\",\"width\":300,\"height\":91,\"caption\":\"Plasnor\"},\"image\":{\"@id\":\"https:\/\/wp.plasnor.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/plasnor-s.a.\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/wp.plasnor.com\/es\/#\/schema\/person\/51769332fbe59a0095b15728faedad84\",\"name\":\"adminadaki@plasnor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/wp.plasnor.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4138537bb142e1506f467f7e58ce2383?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4138537bb142e1506f467f7e58ce2383?s=96&d=mm&r=g\",\"caption\":\"adminadaki@plasnor\"},\"sameAs\":[\"http:\/\/ww2.plasnor.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"03. \u00bfQUE TIPO DE COLA ES NECESARIO APLICAR? - Plasnor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/","og_locale":"es_ES","og_type":"article","og_title":"03. \u00bfQUE TIPO DE COLA ES NECESARIO APLICAR? - Plasnor","og_description":"El pegamento debe ser PUR. No trate de aplicar otros pegamentos, nuestra experiencia nos dice que nunca funcionan ... [ + info ]","og_url":"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/","og_site_name":"Plasnor","article_published_time":"2023-04-21T09:31:08+00:00","article_modified_time":"2023-04-23T15:47:47+00:00","og_image":[{"url":"https:\/\/www.plasnor.com\/wp-content\/uploads\/2023\/04\/icono-link2.gif"}],"author":"adminadaki@plasnor","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/#article","isPartOf":{"@id":"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/"},"author":{"name":"adminadaki@plasnor","@id":"https:\/\/wp.plasnor.com\/es\/#\/schema\/person\/51769332fbe59a0095b15728faedad84"},"headline":"03. \u00bfQUE TIPO DE COLA ES NECESARIO APLICAR?","datePublished":"2023-04-21T09:31:08+00:00","dateModified":"2023-04-23T15:47:47+00:00","mainEntityOfPage":{"@id":"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/"},"wordCount":85,"publisher":{"@id":"https:\/\/wp.plasnor.com\/es\/#organization"},"image":{"@id":"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.plasnor.com\/wp-content\/uploads\/2023\/04\/icono-link2.gif","articleSection":["FAQ"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/","url":"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/","name":"03. \u00bfQUE TIPO DE COLA ES NECESARIO APLICAR? - Plasnor","isPartOf":{"@id":"https:\/\/wp.plasnor.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/#primaryimage"},"image":{"@id":"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.plasnor.com\/wp-content\/uploads\/2023\/04\/icono-link2.gif","datePublished":"2023-04-21T09:31:08+00:00","dateModified":"2023-04-23T15:47:47+00:00","breadcrumb":{"@id":"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/#primaryimage","url":"https:\/\/www.plasnor.com\/wp-content\/uploads\/2023\/04\/icono-link2.gif","contentUrl":"https:\/\/www.plasnor.com\/wp-content\/uploads\/2023\/04\/icono-link2.gif"},{"@type":"BreadcrumbList","@id":"https:\/\/wp.plasnor.com\/es\/03-que-tipo-de-cola-es-necesario-aplicar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wp.plasnor.com\/es\/"},{"@type":"ListItem","position":2,"name":"FAQ","item":"https:\/\/wp.plasnor.com\/es\/category\/faq\/"},{"@type":"ListItem","position":3,"name":"03. \u00bfQUE TIPO DE COLA ES NECESARIO APLICAR?"}]},{"@type":"WebSite","@id":"https:\/\/wp.plasnor.com\/es\/#website","url":"https:\/\/wp.plasnor.com\/es\/","name":"Plasnor","description":"Especialistas en extrusi\u00f3n y termoconformado","publisher":{"@id":"https:\/\/wp.plasnor.com\/es\/#organization"},"alternateName":"Plasnor","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wp.plasnor.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/wp.plasnor.com\/es\/#organization","name":"Plasnor","alternateName":"Plasnor","url":"https:\/\/wp.plasnor.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wp.plasnor.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.plasnor.com\/wp-content\/uploads\/2023\/04\/logotipo-plasnor.jpg","contentUrl":"https:\/\/www.plasnor.com\/wp-content\/uploads\/2023\/04\/logotipo-plasnor.jpg","width":300,"height":91,"caption":"Plasnor"},"image":{"@id":"https:\/\/wp.plasnor.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/plasnor-s.a."]},{"@type":"Person","@id":"https:\/\/wp.plasnor.com\/es\/#\/schema\/person\/51769332fbe59a0095b15728faedad84","name":"adminadaki@plasnor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wp.plasnor.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4138537bb142e1506f467f7e58ce2383?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4138537bb142e1506f467f7e58ce2383?s=96&d=mm&r=g","caption":"adminadaki@plasnor"},"sameAs":["http:\/\/ww2.plasnor.com"]}]}},"_links":{"self":[{"href":"https:\/\/wp.plasnor.com\/es\/wp-json\/wp\/v2\/posts\/176"}],"collection":[{"href":"https:\/\/wp.plasnor.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.plasnor.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.plasnor.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.plasnor.com\/es\/wp-json\/wp\/v2\/comments?post=176"}],"version-history":[{"count":0,"href":"https:\/\/wp.plasnor.com\/es\/wp-json\/wp\/v2\/posts\/176\/revisions"}],"wp:attachment":[{"href":"https:\/\/wp.plasnor.com\/es\/wp-json\/wp\/v2\/media?parent=176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.plasnor.com\/es\/wp-json\/wp\/v2\/categories?post=176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.plasnor.com\/es\/wp-json\/wp\/v2\/tags?post=176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}